{"id":844,"date":"2016-02-16T00:13:35","date_gmt":"2016-02-15T23:13:35","guid":{"rendered":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/?p=844"},"modified":"2023-06-30T12:24:26","modified_gmt":"2023-06-30T11:24:26","slug":"succion-non-nutritive-411-les-interactions-de-la-succion-non-nutritive","status":"publish","type":"post","link":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/2016\/02\/16\/succion-non-nutritive-411-les-interactions-de-la-succion-non-nutritive\/","title":{"rendered":"Succion non-nutritive &#8211; 4\/11 &#8211; Les interactions de la succion non-nutritive"},"content":{"rendered":"<h4>Chaque enfant vivra la gestion de ses \u00e9motions diff\u00e9remment,<\/h4>\n<p><span style=\"color: #333333;\">d\u2019une part en fonction de son \u00e2ge, d\u2019autre part en fonction de son fonctionnement \u00e9motionnel individuel et enfin en fonction de la mani\u00e8re dont les adultes vont traverser la p\u00e9riode de grossesse et construire son arriv\u00e9e dans la famille.<\/span><\/p>\n<p><span style=\"color: #333333;\">Ces interactions d\u00e9pendent de l\u2019\u00e2ge psychique, social et historique, de l\u2019enfant et bien s\u00fbr, de son environnement affectif.<\/span><\/p>\n<p><span style=\"color: #333333;\">Mon premier \u00e9clairage sur la n\u00e9cessit\u00e9 pour l\u2019enfant de t\u00e9ter, est de vous dire que la succion est directement li\u00e9e aux <strong>m\u00e9moires affectives de contenance <\/strong>(embrassement) <strong>de soutenances<\/strong> (pr\u00e9sence maternelle et paternelle) et <strong>de s\u00e9curit\u00e9<\/strong> (nourriture suffisante et bonne).<\/span><\/p>\n<h2>L\u2019enfant na\u00eet en portant une m\u00e9moire de succion non-nutritive et une m\u00e9moire de succion nutritive<strong>.<\/strong><\/h2>\n<p><span style=\"color: #333333;\">Apr\u00e8s la naissance, le b\u00e9b\u00e9 va plus ou moins conforter ou r\u00e9parer ces m\u00e9moires \u00e0 partir de ses nouvelles exp\u00e9riences de nourriture de succion et d\u2019amour.<\/span><\/p>\n<p><span style=\"color: #333333;\">Nous allons voir quand il est pr\u00e9f\u00e9rable ou primordial de quitter le d\u00e9sir de succion, biberon, sucette, pouce.<\/span><br \/>\n<span style=\"color: #333333;\"> La plus grande exp\u00e9rience pour nous humains, qui se consolide et se rejoue tout au long de l\u2019enfance et de la vie est\u00a0: \u00abLA COMP\u00c9TENCE \u00c0 LA S\u00c9PARATION\u00bb.<\/span><br \/>\n<span style=\"color: #333333;\"> Les s\u00e9parations du corps maternel sont multiples et successives\u00a0: l\u2019accouchement, le sommeil seul, l\u2019arr\u00eat de l\u2019allaitement, l\u2019autonomie alimentaire, la marche etc.<\/span><\/p>\n<p><strong><span style=\"color: #333333;\">Le seul t\u00e9moin visible de ces s\u00e9parations sera la succion chez l\u2019enfant.<\/span><\/strong><\/p>\n<p><span style=\"color: #333333;\">Nous savons que tous les \u00e9v\u00e9nements v\u00e9cus par l\u2019enfant dans la p\u00e9riode intra-ut\u00e9rine, vont laisser des traces profond\u00e9ment engramm\u00e9es dans sa m\u00e9moire.<\/span><\/p>\n<p><span style=\"color: #333333;\">Cette m\u00e9moire du petit f\u0153tus se construit en interd\u00e9pendance avec les facult\u00e9s \u00e9motionnelles et psychiques de la m\u00e8re, pendant cette grossesse.<\/span><\/p>\n<p><span style=\"color: #333333;\">Dans certains cas, une m\u00e9moire d\u2019abandon, \u00ab\u00a0d\u2019enveloppement maternel manquant\u00a0\u00bb, d\u2019ins\u00e9curit\u00e9, peut d\u00e9j\u00e0 s\u2019inscrire chez le f\u0153tus en cas de stress maternel important.<\/span><\/p>\n<p><span style=\"color: #333333;\">Une de ses cons\u00e9quences touche en particulier la succion\u00a0du f\u0153tus. L\u2019alt\u00e9ration et l\u2019acidit\u00e9 du liquide amniotique peuvent l\u2019emp\u00eacher de sucer son pouce ou de boire, le laissant na\u00eetre avec des voies endobuccales et \u0153sophagiennes inachev\u00e9es pour la t\u00e9t\u00e9e ou m\u00eame plus tard pour la parole.<\/span><\/p>\n<p><span style=\"color: #333333;\">Les signes de cette m\u00e9moire de stress touchant la succion se voient tout de suite apr\u00e8s la naissance :<\/span><\/p>\n<ul>\n<li><span style=\"color: #333333;\">troubles alimentaires, voire anorexie du nourrisson<\/span><\/li>\n<li><span style=\"color: #333333;\">troubles du sommeil<\/span><\/li>\n<li><span style=\"color: #333333;\">d\u00e9pression pr\u00e9coce<\/span><\/li>\n<li><span style=\"color: #333333;\">besoin extr\u00eame de succion ou incapacit\u00e9 de succion<\/span><\/li>\n<li><span style=\"color: #333333;\">troubles d\u2019expression, pleurs ou non pleurs et, plus tard, troubles du langage<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #333333;\">\u00c0 chaque \u00e2ge, \u00e0 chaque grande \u00e9tape de maturit\u00e9 psychoaffective,<strong> la s\u00e9paration du corps maternel va \u00eatre mim\u00e9e par l\u2019enfant<\/strong> par sa mani\u00e8re de trouver ou non une auto s\u00e9curit\u00e9 buccale.<\/span><\/p>\n<p><span style=\"color: #333333;\">Je vais laisser \u00e0 des sp\u00e9cialistes, les causes physiques et neuromusculaires de n\u00e9cessit\u00e9 de succion, pour ne parler que des raisons psychologiques de ce d\u00e9sir pour l\u2019enfant APR\u00c8S sa naissance.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chaque enfant vivra la gestion de ses \u00e9motions diff\u00e9remment, d\u2019une part en fonction de son \u00e2ge, d\u2019autre part en fonction de son fonctionnement \u00e9motionnel individuel et enfin en fonction de la mani\u00e8re dont les adultes vont traverser la p\u00e9riode de grossesse et construire son arriv\u00e9e dans la famille. Ces interactions d\u00e9pendent de l\u2019\u00e2ge psychique, social&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,1],"tags":[23,17,18,24,10,21,26,22,25,15,16,14,20,19,12,13,11],"class_list":["post-844","post","type-post","status-publish","format-standard","hentry","category-articles","category-article","tag-aix-en-provence","tag-aquatherapie","tag-autisme","tag-eau","tag-enfant","tag-foetoaquatherapie","tag-le-jardin-aquatique","tag-marie-schmitt","tag-mere","tag-nouveau-ne","tag-parent","tag-pouce","tag-psychotherapie","tag-relation","tag-succion","tag-sucette","tag-therapie","category-8","category-1","description-off"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/posts\/844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/comments?post=844"}],"version-history":[{"count":12,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/posts\/844\/revisions"}],"predecessor-version":[{"id":916,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/posts\/844\/revisions\/916"}],"wp:attachment":[{"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/media?parent=844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/categories?post=844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xn--thrapie-eau-mre-enfant-z7bm.fr\/index.php\/wp-json\/wp\/v2\/tags?post=844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}